{"id":12333,"date":"2018-04-21T16:32:03","date_gmt":"2018-04-21T19:32:03","guid":{"rendered":"https:\/\/test2.jacquesbedel.com\/?p=12333"},"modified":"2023-08-22T11:46:46","modified_gmt":"2023-08-22T14:46:46","slug":"memorias-del-subdesarrollo-la-descolonizacion-del-arte-en-america-latina-1960-1985-2018-2","status":"publish","type":"post","link":"https:\/\/jacquesbedel.com\/en\/memorias-del-subdesarrollo-la-descolonizacion-del-arte-en-america-latina-1960-1985-2018-2\/","title":{"rendered":"MEMORIAS DEL SUBDESARROLLO: LA DESCOLONIZACI\u00d3N DEL ARTE EN AM\u00c9RICA LATINA (1960-1985) 2018"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>21\/04\/2018 Fundaci\u00f3n Jumex. DF. M\u00e9xico.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"21\/04\/2018 Fundaci\u00f3n Jumex. DF. M\u00e9xico.","protected":false},"author":1,"featured_media":10246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[95],"tags":[],"class_list":["post-12333","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-exposiciones-colectivas","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12333"}],"collection":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/comments?post=12333"}],"version-history":[{"count":1,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12333\/revisions"}],"predecessor-version":[{"id":12334,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12333\/revisions\/12334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/media\/10246"}],"wp:attachment":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/media?parent=12333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/categories?post=12333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/tags?post=12333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}