{"id":12412,"date":"2013-04-03T17:35:28","date_gmt":"2013-04-03T20:35:28","guid":{"rendered":"https:\/\/test2.jacquesbedel.com\/?p=12412"},"modified":"2023-08-22T11:06:23","modified_gmt":"2023-08-22T14:06:23","slug":"aipad-2013","status":"publish","type":"post","link":"https:\/\/jacquesbedel.com\/en\/aipad-2013\/","title":{"rendered":"AIPAD 2013"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>03\/04\/2013 Jacques Bedel, Galer\u00eda Vasari, AIPAD, Park Avenue Armory, New York.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"03\/04\/2013 Jacques Bedel, Galer\u00eda Vasari, AIPAD, Park Avenue Armory, New York.","protected":false},"author":1,"featured_media":10133,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[95],"tags":[],"class_list":["post-12412","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-exposiciones-colectivas","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12412"}],"collection":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/comments?post=12412"}],"version-history":[{"count":1,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12412\/revisions"}],"predecessor-version":[{"id":12413,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12412\/revisions\/12413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/media\/10133"}],"wp:attachment":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/media?parent=12412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/categories?post=12412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/tags?post=12412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}