{"id":12418,"date":"2012-10-17T17:40:51","date_gmt":"2012-10-17T20:40:51","guid":{"rendered":"https:\/\/test2.jacquesbedel.com\/?p=12418"},"modified":"2023-08-22T11:05:05","modified_gmt":"2023-08-22T14:05:05","slug":"eggo-2012","status":"publish","type":"post","link":"https:\/\/jacquesbedel.com\/en\/eggo-2012\/","title":{"rendered":"EGGO 2012"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>17\/10\/2012 Galer\u00eda Sasha D. Espacio de Arte. Centro Cultural Recoleta. Argentina.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"17\/10\/2012 Galer\u00eda Sasha D. Espacio de Arte. Centro Cultural Recoleta. Argentina.","protected":false},"author":1,"featured_media":10204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[95],"tags":[],"class_list":["post-12418","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-exposiciones-colectivas","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12418"}],"collection":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/comments?post=12418"}],"version-history":[{"count":1,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12418\/revisions"}],"predecessor-version":[{"id":12419,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12418\/revisions\/12419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/media\/10204"}],"wp:attachment":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/media?parent=12418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/categories?post=12418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/tags?post=12418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}