{"id":12620,"date":"1980-02-01T15:08:53","date_gmt":"1980-02-01T18:08:53","guid":{"rendered":"https:\/\/test2.jacquesbedel.com\/?p=12620"},"modified":"2023-08-22T10:03:30","modified_gmt":"2023-08-22T13:03:30","slug":"i-bienal-internacional-de-arte-de-montevideo-1980","status":"publish","type":"post","link":"https:\/\/jacquesbedel.com\/en\/i-bienal-internacional-de-arte-de-montevideo-1980\/","title":{"rendered":"I BIENAL INTERNACIONAL DE ARTE DE MONTEVIDEO 1980"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>01\/02\/1980 Museo Nacional de Artes Pl\u00e1sticas. Montevideo.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"01\/02\/1980 Museo Nacional de Artes Pl\u00e1sticas. Montevideo.","protected":false},"author":1,"featured_media":9871,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[95],"tags":[],"class_list":["post-12620","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-exposiciones-colectivas","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12620"}],"collection":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/comments?post=12620"}],"version-history":[{"count":1,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12620\/revisions"}],"predecessor-version":[{"id":12621,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12620\/revisions\/12621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/media\/9871"}],"wp:attachment":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/media?parent=12620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/categories?post=12620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/tags?post=12620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}