{"id":12696,"date":"1971-01-27T16:19:56","date_gmt":"1971-01-27T19:19:56","guid":{"rendered":"https:\/\/test2.jacquesbedel.com\/?p=12696"},"modified":"2023-08-22T09:27:00","modified_gmt":"2023-08-22T12:27:00","slug":"panorama-de-experiencias-visuales-1971","status":"publish","type":"post","link":"https:\/\/jacquesbedel.com\/en\/panorama-de-experiencias-visuales-1971\/","title":{"rendered":"PANORAMA DE EXPERIENCIAS VISUALES 1971"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>27\/01\/1971 Fundaci\u00f3n Lorenzutti. Museo de Arte Moderno de Buenos Aires.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"27\/01\/1971 Fundaci\u00f3n Lorenzutti. Museo de Arte Moderno de Buenos Aires.","protected":false},"author":1,"featured_media":9803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[95],"tags":[],"class_list":["post-12696","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-exposiciones-colectivas","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12696"}],"collection":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/comments?post=12696"}],"version-history":[{"count":1,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12696\/revisions"}],"predecessor-version":[{"id":12697,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/posts\/12696\/revisions\/12697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/media\/9803"}],"wp:attachment":[{"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/media?parent=12696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/categories?post=12696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jacquesbedel.com\/en\/wp-json\/wp\/v2\/tags?post=12696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}